{"id":9267,"date":"2021-12-27T11:16:39","date_gmt":"2021-12-27T14:16:39","guid":{"rendered":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl012-fd-0001\/"},"modified":"2021-12-27T11:16:39","modified_gmt":"2021-12-27T14:16:39","slug":"sl012-fd-0001","status":"publish","type":"product","link":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl012-fd-0001\/","title":{"rendered":"SL012-FD-0001"},"content":{"rendered":"<p>Carnaval 1995 &#8211; Infantil Orpheu; Carnaval; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carnaval 1995 &#8211; Infantil Orpheu; Carnaval;<\/p>\n","protected":false},"featured_media":9266,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[45],"product_tag":[],"class_list":["post-9267","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-carnaval"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product\/9267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/comments?post=9267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media\/9266"}],"wp:attachment":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media?parent=9267"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=9267"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=9267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}