{"id":54198,"date":"2022-01-26T15:26:42","date_gmt":"2022-01-26T18:26:42","guid":{"rendered":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl085-fd-0618\/"},"modified":"2022-01-26T15:26:42","modified_gmt":"2022-01-26T18:26:42","slug":"sl085-fd-0618","status":"publish","type":"product","link":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl085-fd-0618\/","title":{"rendered":"SL085-FD-0618"},"content":{"rendered":"<p>Enchente, 27\/09\/1926 Rua Brasil. &#8211; C\u00f3digo anterior de cat\u00e1logo:FD 85 2-118; Rio dos Sinos; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enchente, 27\/09\/1926 Rua Brasil. &#8211; C\u00f3digo anterior de cat\u00e1logo:FD 85 2-118; Rio dos Sinos;<\/p>\n","protected":false},"featured_media":54197,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[117],"product_tag":[],"class_list":["post-54198","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-rio-dos-sinos"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product\/54198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/comments?post=54198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media\/54197"}],"wp:attachment":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media?parent=54198"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=54198"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=54198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}