{"id":51074,"date":"2022-01-24T09:51:31","date_gmt":"2022-01-24T12:51:31","guid":{"rendered":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl081-fd-0063\/"},"modified":"2022-01-24T09:51:31","modified_gmt":"2022-01-24T12:51:31","slug":"sl081-fd-0063","status":"publish","type":"product","link":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl081-fd-0063\/","title":{"rendered":"SL081-FD-0063"},"content":{"rendered":"<p>Local onde est\u00e1 localizada atualmente a Pra\u00e7a G\u00f3is Monteiro, conhecida como &#8220;Tri\u00e2ngulo&#8221;, nas esquinas das ruas Lindolfo Collor e Saldanha da Gama. &#8211; C\u00f3digo anterior de cat\u00e1logo:FD 81-63; Pra\u00e7as &#8211; S\u00e3o Leopoldo; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Local onde est\u00e1 localizada atualmente a Pra\u00e7a G\u00f3is Monteiro, conhecida como &#8220;Tri\u00e2ngulo&#8221;, nas esquinas das ruas Lindolfo Collor e Saldanha<\/p>\n","protected":false},"featured_media":51073,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[114],"product_tag":[],"class_list":["post-51074","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-pracas-sao-leopoldo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product\/51074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/comments?post=51074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media\/51073"}],"wp:attachment":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media?parent=51074"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=51074"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=51074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}