{"id":51044,"date":"2022-01-24T09:51:10","date_gmt":"2022-01-24T12:51:10","guid":{"rendered":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl081-fd-0048\/"},"modified":"2022-01-24T09:51:10","modified_gmt":"2022-01-24T12:51:10","slug":"sl081-fd-0048","status":"publish","type":"product","link":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl081-fd-0048\/","title":{"rendered":"SL081-FD-0048"},"content":{"rendered":"<p>Inaugura\u00e7\u00e3o do pr\u00e9dio da Prefeitura Municipal de S\u00e3o Leopoldo, em 1940.  &#8211; C\u00f3digo anterior de cat\u00e1logo:FD 81-48; Pra\u00e7as &#8211; S\u00e3o Leopoldo; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inaugura\u00e7\u00e3o do pr\u00e9dio da Prefeitura Municipal de S\u00e3o Leopoldo, em 1940. &#8211; C\u00f3digo anterior de cat\u00e1logo:FD 81-48; Pra\u00e7as &#8211; S\u00e3o<\/p>\n","protected":false},"featured_media":51043,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[114],"product_tag":[],"class_list":["post-51044","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-pracas-sao-leopoldo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product\/51044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/comments?post=51044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media\/51043"}],"wp:attachment":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media?parent=51044"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=51044"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=51044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}