{"id":37451,"date":"2022-01-14T09:00:29","date_gmt":"2022-01-14T12:00:29","guid":{"rendered":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl025-fd-0331\/"},"modified":"2022-01-14T09:00:29","modified_gmt":"2022-01-14T12:00:29","slug":"sl025-fd-0331","status":"publish","type":"product","link":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl025-fd-0331\/","title":{"rendered":"SL025-FD-0331"},"content":{"rendered":"<p>Escoteiros Cruzeiros do Sul, Grupo de Escoteiros Cruzeiro do Sul; Grupos e clubes de Servi\u00e7os: Lions, Girassol, Rotary, Soroptmista, Escoteiros, Amencar, etc; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escoteiros Cruzeiros do Sul, Grupo de Escoteiros Cruzeiro do Sul; Grupos e clubes de Servi\u00e7os: Lions, Girassol, Rotary, Soroptmista, Escoteiros,<\/p>\n","protected":false},"featured_media":37450,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[92,91,93,88,87,89,90],"product_tag":[],"class_list":["post-37451","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-amencar","product_cat-escoteiros","product_cat-etc","product_cat-girassol","product_cat-grupos-e-clubes-de-servicos-lions","product_cat-rotary","product_cat-soroptmista"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product\/37451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/comments?post=37451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media\/37450"}],"wp:attachment":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media?parent=37451"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=37451"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=37451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}