{"id":27579,"date":"2022-01-06T08:43:00","date_gmt":"2022-01-06T11:43:00","guid":{"rendered":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl036-fd-1313\/"},"modified":"2022-01-06T08:43:00","modified_gmt":"2022-01-06T11:43:00","slug":"sl036-fd-1313","status":"publish","type":"product","link":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl036-fd-1313\/","title":{"rendered":"SL036-FD-1313"},"content":{"rendered":"<p>II Olimp\u00edada, Bol\u00e3o de Casais, Equipe do Peleia; Esportes; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>II Olimp\u00edada, Bol\u00e3o de Casais, Equipe do Peleia; Esportes;<\/p>\n","protected":false},"featured_media":27578,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[61],"product_tag":[],"class_list":["post-27579","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-esportes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product\/27579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/comments?post=27579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media\/27578"}],"wp:attachment":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media?parent=27579"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=27579"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=27579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}