{"id":24680,"date":"2022-01-05T10:27:29","date_gmt":"2022-01-05T13:27:29","guid":{"rendered":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl033-fd-1767\/"},"modified":"2022-01-05T10:27:29","modified_gmt":"2022-01-05T13:27:29","slug":"sl033-fd-1767","status":"publish","type":"product","link":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl033-fd-1767\/","title":{"rendered":"SL033-FD-1767"},"content":{"rendered":"<p>Escola Estadual Frederico Guilherme Schmidt, Ato de assinatura entre a construtec e o COM do Tio Fredy; Escolas; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escola Estadual Frederico Guilherme Schmidt, Ato de assinatura entre a construtec e o COM do Tio Fredy; Escolas;<\/p>\n","protected":false},"featured_media":24679,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[60],"product_tag":[],"class_list":["post-24680","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-escolas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product\/24680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/comments?post=24680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media\/24679"}],"wp:attachment":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media?parent=24680"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=24680"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=24680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}