{"id":24596,"date":"2022-01-05T10:26:28","date_gmt":"2022-01-05T13:26:28","guid":{"rendered":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl033-fd-1725\/"},"modified":"2022-01-05T10:26:28","modified_gmt":"2022-01-05T13:26:28","slug":"sl033-fd-1725","status":"publish","type":"product","link":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl033-fd-1725\/","title":{"rendered":"SL033-FD-1725"},"content":{"rendered":"<p>Escola Estadual Professor Em\u00edlio Boeckel de I Grau Incompleto, Bairro Rio dos Sinos, Lya Maria Petry Seelig empossando Solange Tesser como diretora da Escola, 04\/05\/1983; Escolas; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escola Estadual Professor Em\u00edlio Boeckel de I Grau Incompleto, Bairro Rio dos Sinos, Lya Maria Petry Seelig empossando Solange Tesser<\/p>\n","protected":false},"featured_media":24595,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[60],"product_tag":[],"class_list":["post-24596","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-escolas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product\/24596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/comments?post=24596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media\/24595"}],"wp:attachment":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media?parent=24596"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=24596"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=24596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}