{"id":19654,"date":"2022-01-04T09:23:52","date_gmt":"2022-01-04T12:23:52","guid":{"rendered":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl034-fd-0073\/"},"modified":"2022-01-04T09:23:52","modified_gmt":"2022-01-04T12:23:52","slug":"sl034-fd-0073","status":"publish","type":"product","link":"https:\/\/www.museuhistoricosl.com.br\/loja\/produto\/sl034-fd-0073\/","title":{"rendered":"SL034-FD-0073"},"content":{"rendered":"<p>Escola Estadual de 1\u00ba Grau Visconde de S\u00e3o Leopoldo, 1983, Liana Brand\u00e3o, falando aos alunos do Visconde de S\u00e3o Leopoldo sobre sua arte; Escola Estadual Visconde de S\u00e3o Leopoldo; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escola Estadual de 1\u00ba Grau Visconde de S\u00e3o Leopoldo, 1983, Liana Brand\u00e3o, falando aos alunos do Visconde de S\u00e3o Leopoldo<\/p>\n","protected":false},"featured_media":19653,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[58],"product_tag":[],"class_list":["post-19654","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-escola-estadual-visconde-de-sao-leopoldo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product\/19654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/comments?post=19654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media\/19653"}],"wp:attachment":[{"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/media?parent=19654"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=19654"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.museuhistoricosl.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=19654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}